{"id":25,"count":13,"description":"","link":"https:\/\/www.mpdspace.com\/blog\/category\/time-management\/personal-management\/","name":"Personal management","slug":"personal-management","taxonomy":"category","parent":24,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.mpdspace.com\/blog\/category\/time-management\/personal-management\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mpdspace.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/25\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.mpdspace.com\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mpdspace.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.mpdspace.com\\\/blog\\\/category\\\/time-management\\\/#listItem\",\"name\":\"Time management\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.mpdspace.com\\\/blog\\\/category\\\/time-management\\\/#listItem\",\"position\":2,\"name\":\"Time management\",\"item\":\"https:\\\/\\\/www.mpdspace.com\\\/blog\\\/category\\\/time-management\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.mpdspace.com\\\/blog\\\/category\\\/time-management\\\/personal-management\\\/#listItem\",\"name\":\"Personal management\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.mpdspace.com\\\/blog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.mpdspace.com\\\/blog\\\/category\\\/time-management\\\/personal-management\\\/#listItem\",\"position\":3,\"name\":\"Personal management\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.mpdspace.com\\\/blog\\\/category\\\/time-management\\\/#listItem\",\"name\":\"Time management\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.mpdspace.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/25\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.mpdspace.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/25\\\/\",\"name\":\"Personal management - My personal development space\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mpdspace.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mpdspace.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/25\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mpdspace.com\\\/blog\\\/#organization\",\"name\":\"My personal development space\",\"description\":\"Personal development for progressive people blog\",\"url\":\"https:\\\/\\\/www.mpdspace.com\\\/blog\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mpdspace.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.mpdspace.com\\\/blog\\\/\",\"name\":\"My personal development space\",\"description\":\"Personal development for progressive people blog\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mpdspace.com\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Personal management - My personal development space","description":"","canonical_url":"https:\/\/www.mpdspace.com\/blog\/category\/time-management\/personal-management\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.mpdspace.com\/blog\/wp-json\/wp\/v2\/categories\/25\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.mpdspace.com\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.mpdspace.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.mpdspace.com\/blog\/category\/time-management\/#listItem","name":"Time management"}},{"@type":"ListItem","@id":"https:\/\/www.mpdspace.com\/blog\/category\/time-management\/#listItem","position":2,"name":"Time management","item":"https:\/\/www.mpdspace.com\/blog\/category\/time-management\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.mpdspace.com\/blog\/category\/time-management\/personal-management\/#listItem","name":"Personal management"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.mpdspace.com\/blog#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.mpdspace.com\/blog\/category\/time-management\/personal-management\/#listItem","position":3,"name":"Personal management","previousItem":{"@type":"ListItem","@id":"https:\/\/www.mpdspace.com\/blog\/category\/time-management\/#listItem","name":"Time management"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.mpdspace.com\/blog\/wp-json\/wp\/v2\/categories\/25\/#collectionpage","url":"https:\/\/www.mpdspace.com\/blog\/wp-json\/wp\/v2\/categories\/25\/","name":"Personal management - My personal development space","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.mpdspace.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.mpdspace.com\/blog\/wp-json\/wp\/v2\/categories\/25\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.mpdspace.com\/blog\/#organization","name":"My personal development space","description":"Personal development for progressive people blog","url":"https:\/\/www.mpdspace.com\/blog\/"},{"@type":"WebSite","@id":"https:\/\/www.mpdspace.com\/blog\/#website","url":"https:\/\/www.mpdspace.com\/blog\/","name":"My personal development space","description":"Personal development for progressive people blog","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.mpdspace.com\/blog\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.mpdspace.com\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.mpdspace.com\/blog\/category\/time-management\/\" title=\"Time management\">Time management<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPersonal management\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.mpdspace.com\/blog"},{"label":"Time management","link":"https:\/\/www.mpdspace.com\/blog\/category\/time-management\/"},{"label":"Personal management","link":"https:\/\/www.mpdspace.com\/blog\/category\/time-management\/personal-management\/"}],"_links":{"self":[{"href":"https:\/\/www.mpdspace.com\/blog\/wp-json\/wp\/v2\/categories\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mpdspace.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.mpdspace.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.mpdspace.com\/blog\/wp-json\/wp\/v2\/categories\/24"}],"wp:post_type":[{"href":"https:\/\/www.mpdspace.com\/blog\/wp-json\/wp\/v2\/posts?categories=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}